{"id":15083,"date":"2019-01-08T13:52:05","date_gmt":"2019-01-08T13:52:05","guid":{"rendered":"https:\/\/www.motrec.com\/?p=15083\/"},"modified":"2019-01-08T14:35:42","modified_gmt":"2019-01-08T14:35:42","slug":"garantie-3-ans","status":"publish","type":"post","link":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/","title":{"rendered":"Les garanties de Motrec : parmi les meilleures de l\u2019industrie"},"content":{"rendered":"<p>Les v\u00e9hicules Motrec sont reconnus pour leurs caract\u00e9ristiques s\u00e9curitaires et leur conception ergonomique. Ils sont toutefois encore plus r\u00e9put\u00e9s pour leur robustesse et leur fiabilit\u00e9 in\u00e9gal\u00e9es. En effet, les v\u00e9hicules Motrec sont mis \u00e0 rude \u00e9preuve dans les conditions les plus exigeantes, par souci de performance.<\/p>\n<p>Pourquoi nos v\u00e9hicules sont-ils aussi fiables? Entre autres, parce que nous utilisons des pi\u00e8ces de qualit\u00e9 sup\u00e9rieure et que nous veillons \u00e0 les utiliser dans plusieurs v\u00e9hicules afin qu\u2019elles soient interchangeables. De plus, nos v\u00e9hicules sont soumis \u00e0 des tests rigoureux.<\/p>\n<p>Les clients de Motrec de partout dans le monde s\u2019attendent \u00e0 pouvoir compter sur des v\u00e9hicules qui offrent une performance durable et qui demandent un minimum d\u2019entretien \u2013 qu\u2019ils aient un seul <a href=\"https:\/\/www.motrec.com\/fr\/vehicules\/series\/serie-ms\/ms-260\/\">chariot de magasinier<\/a> ou toute une flotte de <a href=\"https:\/\/www.motrec.com\/fr\/vehicules\/series\/serie-mt\/\">tracteurs de remorquage<\/a> con\u00e7us enti\u00e8rement sur mesure.<\/p>\n<p>Nous sommes heureux d\u2019annoncer que nos nouvelles garanties refl\u00e8teront d\u00e9sormais ces avantages. \u00c0 compter du 1<sup>er<\/sup>\u00a0janvier\u00a02019, les produits Motrec seront assortis des garanties suivantes\u00a0:<\/p>\n<p><strong>Garantie limit\u00e9e de trois\u00a0ans sur\u00a0:<\/strong><\/p>\n<ul>\n<li>Tous les v\u00e9hicules Motrec fonctionnant par <a href=\"https:\/\/www.motrec.com\/fr\/innovation\/groupe-motopropulseur-courant-alternatif\/\">courant alternatif<\/a>;<\/li>\n<li>Nos chariots de magasiniers <a href=\"https:\/\/www.motrec.com\/fr\/vehicules\/series\/serie-ms\/ms-260\/\">MS-260<\/a>;<\/li>\n<li>Toutes les <a href=\"https:\/\/www.motrec.com\/fr\/remorques\/\">remorques<\/a> Motrec.<\/li>\n<\/ul>\n<p><strong><br \/>\nGarantie limit\u00e9e de deux\u00a0ans sur\u00a0:<\/strong><\/p>\n<ul>\n<li>Tous les v\u00e9hicules Motrec fonctionnant par courant continu;<\/li>\n<li>Tous les autres v\u00e9hicules Motrec<\/li>\n<\/ul>\n<blockquote><p>\u00ab Motrec est maintenant le chef de file dans le domaine des v\u00e9hicules \u00e9lectriques industriels, et la raison en est fort simple : notre \u00e9quipe s\u2019emploie sans rel\u00e2che \u00e0 concevoir et \u00e0 construire des machines indestructibles qui offrent une fiabilit\u00e9 \u00e0 long terme. Inscrire nos garanties parmi les meilleures de l\u2019industrie d\u00e9montre bien dans quelle mesure nous avons confiance en nos v\u00e9hicules de premi\u00e8re qualit\u00e9.\u00bb<\/p>\n<p>\u2013 Blair McIntosh, pr\u00e9sident<\/p><\/blockquote>\n<p>Vous voulez en apprendre davantage sur les garanties de Motrec? Visitez la section <a href=\"https:\/\/www.motrec.com\/fr\/garantie\/\">g<u>aranties<\/u><\/a> de notre site Web ou <a href=\"https:\/\/www.motrec.com\/fr\/nous-joindre\/\">communiquez avec nous<\/a> pour parler \u00e0 un repr\u00e9sentant Motrec.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Garantie limit\u00e9e de trois ans sur les produits avec moteur \u00e0 courant alternatif, les chariots de magasiniers et les remorques. Ces garanties sont applicables sur les commandes re\u00e7ues \u00e0 partir du 1er janvier 2019.<\/p>\n","protected":false},"author":100,"featured_media":15124,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[19],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les garanties de Motrec : parmi les meilleures de l\u2019industrie | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les garanties de Motrec : parmi les meilleures de l\u2019industrie | Motrec\" \/>\n<meta property=\"og:description\" content=\"Garantie limit\u00e9e de trois ans sur les produits avec moteur \u00e0 courant alternatif, les chariots de magasiniers et les remorques. Ces garanties sont applicables sur les commandes re\u00e7ues \u00e0 partir du 1er janvier 2019.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-08T13:52:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-08T14:35:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/01\/BlogPost-Header-Warranty.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime Champagne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/01\/BlogPost-Header-Warranty.jpg\",\"contentUrl\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/01\/BlogPost-Header-Warranty.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/\",\"name\":\"Les garanties de Motrec : parmi les meilleures de l\\u2019industrie | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#primaryimage\"},\"datePublished\":\"2019-01-08T13:52:05+00:00\",\"dateModified\":\"2019-01-08T14:35:42+00:00\",\"author\":{\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les garanties de Motrec : parmi les meilleures de l\\u2019industrie\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d\",\"name\":\"Maxime Champagne\",\"url\":\"https:\/\/dev.motrec.com\/fr\/author\/maxime\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les garanties de Motrec : parmi les meilleures de l\u2019industrie | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Les garanties de Motrec : parmi les meilleures de l\u2019industrie | Motrec","og_description":"Garantie limit\u00e9e de trois ans sur les produits avec moteur \u00e0 courant alternatif, les chariots de magasiniers et les remorques. Ces garanties sont applicables sur les commandes re\u00e7ues \u00e0 partir du 1er janvier 2019.","og_url":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_published_time":"2019-01-08T13:52:05+00:00","article_modified_time":"2019-01-08T14:35:42+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/01\/BlogPost-Header-Warranty.jpg","type":"image\/jpeg"}],"twitter_misc":{"\u00c9crit par":"Maxime Champagne","Dur\u00e9e de lecture est.":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/01\/BlogPost-Header-Warranty.jpg","contentUrl":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/01\/BlogPost-Header-Warranty.jpg","width":1200,"height":675},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#webpage","url":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/","name":"Les garanties de Motrec : parmi les meilleures de l\u2019industrie | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#primaryimage"},"datePublished":"2019-01-08T13:52:05+00:00","dateModified":"2019-01-08T14:35:42+00:00","author":{"@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d"},"breadcrumb":{"@id":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/fr\/garantie-3-ans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les garanties de Motrec : parmi les meilleures de l\u2019industrie"}]},{"@type":"Person","@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d","name":"Maxime Champagne","url":"https:\/\/dev.motrec.com\/fr\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts\/15083"}],"collection":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/comments?post=15083"}],"version-history":[{"count":8,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts\/15083\/revisions"}],"predecessor-version":[{"id":15149,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts\/15083\/revisions\/15149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/media\/15124"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/media?parent=15083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/categories?post=15083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/tags?post=15083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}