{"id":12122,"date":"2015-04-28T19:16:14","date_gmt":"2015-04-28T19:16:14","guid":{"rendered":"https:\/\/motrec.bravad-dev.com\/power-to-save-lives\/"},"modified":"2017-03-21T17:45:32","modified_gmt":"2017-03-21T17:45:32","slug":"nous-avons-tous-le-pouvoir-de-sauver-des-vies","status":"publish","type":"post","link":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/","title":{"rendered":"Nous avons tous le pouvoir de sauver des vies"},"content":{"rendered":"<p>Peu d\u2019entre nous le sauraient. Pourtant, chaque ann\u00e9e aux \u00c9tats-Unis, pr\u00e8s de 300 000 personnes subissent un arr\u00eat cardiaque sans signes avant-coureurs. Malheureusement, aussi peu que 7 % d\u2019entre elles survivront, souvent parce que les services d\u2019urgence ne peuvent les rejoindre \u00e0 temps. Chaque minute qui passe r\u00e9duit de 10 % la possibilit\u00e9 d\u2019une r\u00e9animation r\u00e9ussie.<\/p>\n<h2>Chez Motrec nous avons toujours la s\u00e9curit\u00e9 \u00e0 c\u0153ur.<\/h2>\n<p>Apr\u00e8s tout, d\u2019innombrables et vaillants travailleurs partout dans le monde comptent sur nos v\u00e9hicules \u00e9lectriques pour effectuer leurs t\u00e2ches de fa\u00e7on s\u00e9curitaire lors d\u2019utilisations commerciales et industrielles qui repr\u00e9sentent parfois tout un d\u00e9fi.<\/p>\n<p>Cette confiance est sacr\u00e9e pour nous. Alors quand Jean-S\u00e9bastien Duguay, notre Directeur marketing, a propos\u00e9 que nous investissions dans un d\u00e9fibrillateur externe automatique pour nos installations, tout \u00e0 coup le sujet de la s\u00e9curit\u00e9 nous touchait encore de plus pr\u00e8s.<\/p>\n<p><strong>Ensuite il nous a montr\u00e9 des statistiques tr\u00e8s convaincantes.<\/strong><\/p>\n<p>Par exemple, le taux de survie des victimes d\u2019un arr\u00eat cardiaque grimpe \u00e0 75 % ou plus si, pendant les 12 premi\u00e8res minutes, on intervient avec une r\u00e9animation cardio-respiratoire (RCR) et un d\u00e9fibrillateur. La diff\u00e9rence entre un taux de survie de 7 et de 75 % nous a \u00e9norm\u00e9ment marqu\u00e9s.<\/p>\n<p>Apr\u00e8s avoir constat\u00e9 le faible co\u00fbt pour installer un d\u00e9fibrillateur sur place, et comment il \u00e9tait facile, pour pratiquement tout le monde, de l\u2019utiliser sans formation pr\u00e9alable, la d\u00e9cision d\u2019investir dans un d\u00e9fibrillateur \u00e9tait facile. Notre nouveau d\u00e9fibrillateur donne des instructions vocales qui vous guident \u00e0 travers chaque \u00e9tape tout en suivant votre rythme, de sorte que vous savez exactement quoi faire et quand le faire.<br \/>\nAlors maintenant, en plus des autres mesures et programmes que nous avons mis en place pour assurer un environnement de travail sain et s\u00e9curitaire \u00e0 notre personnel, nous avons aussi un outil pratique que n\u2019importe qui d\u2019entre nous peut utiliser \u00e0 tout moment pour possiblement sauver la vie d\u2019un coll\u00e8gue. Nous savons qu\u2019un d\u00e9fibrillateur ne peut sauver toutes les vies, mais il est tr\u00e8s rassurant de savoir qu\u2019il est l\u00e0.<\/p>\n<p>Nous encourageons tous nos partenaires mondiaux (clients de Motrec, concessionnaires ou fournisseurs) \u00e0 consid\u00e9rer l\u2019investissement pour obtenir un d\u00e9fibrillateur dans leurs installations.<\/p>\n<p>Vous trouverez plus d\u2019informations sur les d\u00e9fibrillateurs externes automatis\u00e9s sur le site d\u2019une organisation du gouvernement am\u00e9ricain, la Occupational Safety &amp; Health Administration, au : <a href=\"http:\/\/www.osha.gov\/SLTC\/aed\/\" target=\"_blank\">www.osha.gov\/SLTC\/aed\/<\/a>.<\/p>\n<p><center><img loading=\"lazy\" class=\" wp-image-5442 size-full aligncenter\" src=\"\/wp-content\/uploads\/2015\/04\/philippes.jpg\" alt=\"philippes\" width=\"356\" height=\"265\" srcset=\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/philippes.jpg 356w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/philippes-300x223.jpg 300w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/philippes-320x238.jpg 320w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/philippes-218x162.jpg 218w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/philippes-81x60.jpg 81w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/philippes-56x42.jpg 56w\" sizes=\"(max-width: 356px) 100vw, 356px\" \/><\/center><\/p>\n<h3>QU\u2019EST-CE QUE LA MORT SUBITE D\u2019ORIGINE CARDIAQUE (MSOC)?<\/h3>\n<p>Une MSOC se produit g\u00e9n\u00e9ralement quand le syst\u00e8me \u00e9lectrique du c\u0153ur devient chaotique et cesse de battre correctement. Au fur et \u00e0 mesure que le flux sanguin de l\u2019individu diminue, il ou elle cesse de respirer normalement et devient inconscient.<\/p>\n<h3>QUE FAIT UN D\u00c9FIBRILLATEUR EXTERNE AUTOMATIS\u00c9 (DEA)?<\/h3>\n<p>Un d\u00e9fibrillateur externe automatis\u00e9 est un appareil portatif et l\u00e9ger, qui fonctionne avec des piles et qui est connect\u00e9 \u00e0 des \u00e9lectrodes autoadh\u00e9rantes.<br \/>\nCes capteurs sont appos\u00e9s sur la poitrine de la personne et transmettent des informations sur son rythme cardiaque \u00e0 l\u2019ordinateur int\u00e9gr\u00e9 au DEA. L\u2019ordinateur analyse ensuite ce rythme et d\u00e9termine si une d\u00e9charge \u00e9lectrique est n\u00e9cessaire. Si c\u2019est le cas, la fonction vocale du DEA vous indique \u00e0 quel moment effectuer la d\u00e9charge, et les \u00e9lectrodes effectuent ensuite cette d\u00e9charge.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si quelqu\u2019un \u00e0 votre lieu de travail avait soudainement un arr\u00eat cardiaque, sauriez-vous quoi faire?<\/p>\n","protected":false},"author":2,"featured_media":10199,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nous avons tous le pouvoir de sauver des vies | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nous avons tous le pouvoir de sauver des vies | Motrec\" \/>\n<meta property=\"og:description\" content=\"Si quelqu\u2019un \u00e0 votre lieu de travail avait soudainement un arr\u00eat cardiaque, sauriez-vous quoi faire?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-28T19:16:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-03-21T17:45:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/HeartAttack.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"motrec\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/HeartAttack.jpg\",\"contentUrl\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/HeartAttack.jpg\",\"width\":835,\"height\":470},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/\",\"name\":\"Nous avons tous le pouvoir de sauver des vies | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#primaryimage\"},\"datePublished\":\"2015-04-28T19:16:14+00:00\",\"dateModified\":\"2017-03-21T17:45:32+00:00\",\"author\":{\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nous avons tous le pouvoir de sauver des vies\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad\",\"name\":\"motrec\",\"url\":\"https:\/\/dev.motrec.com\/fr\/author\/motrec\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nous avons tous le pouvoir de sauver des vies | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Nous avons tous le pouvoir de sauver des vies | Motrec","og_description":"Si quelqu\u2019un \u00e0 votre lieu de travail avait soudainement un arr\u00eat cardiaque, sauriez-vous quoi faire?","og_url":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_published_time":"2015-04-28T19:16:14+00:00","article_modified_time":"2017-03-21T17:45:32+00:00","og_image":[{"width":835,"height":470,"url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/HeartAttack.jpg","type":"image\/jpeg"}],"twitter_misc":{"\u00c9crit par":"motrec","Dur\u00e9e de lecture est.":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","@id":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#primaryimage","inLanguage":"fr-FR","url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/HeartAttack.jpg","contentUrl":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2015\/04\/HeartAttack.jpg","width":835,"height":470},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#webpage","url":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/","name":"Nous avons tous le pouvoir de sauver des vies | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#primaryimage"},"datePublished":"2015-04-28T19:16:14+00:00","dateModified":"2017-03-21T17:45:32+00:00","author":{"@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad"},"breadcrumb":{"@id":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/fr\/nous-avons-tous-le-pouvoir-de-sauver-des-vies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Nous avons tous le pouvoir de sauver des vies"}]},{"@type":"Person","@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad","name":"motrec","url":"https:\/\/dev.motrec.com\/fr\/author\/motrec\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts\/12122"}],"collection":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/comments?post=12122"}],"version-history":[{"count":2,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts\/12122\/revisions"}],"predecessor-version":[{"id":12124,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/posts\/12122\/revisions\/12124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/media\/10199"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/media?parent=12122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/categories?post=12122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/tags?post=12122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}