{"id":11336,"date":"2015-05-06T18:09:50","date_gmt":"2015-05-06T18:09:50","guid":{"rendered":"https:\/\/motrec.bravad-dev.com\/trailers\/"},"modified":"2020-07-10T00:36:35","modified_gmt":"2020-07-10T00:36:35","slug":"remorques","status":"publish","type":"page","link":"https:\/\/dev.motrec.com\/fr\/remorques\/","title":{"rendered":"Remorques industrielles"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Remorques industrielles | Motrec<\/title>\n<meta name=\"description\" content=\"Gr\u00e2ce \u00e0 un rayon de braquage r\u00e9duit et \u00e0 une capacit\u00e9 de travail imposante, nos remorques industrielles \u00e0 timon d\u2019attelage sont puissantes et robustes, tout en \u00e9tant hautement man\u0153uvrables.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remorques industrielles | Motrec\" \/>\n<meta property=\"og:description\" content=\"Gr\u00e2ce \u00e0 un rayon de braquage r\u00e9duit et \u00e0 une capacit\u00e9 de travail imposante, nos remorques industrielles \u00e0 timon d\u2019attelage sont puissantes et robustes, tout en \u00e9tant hautement man\u0153uvrables.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/fr\/remorques\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-10T00:36:35+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/remorques\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/fr\/remorques\/\",\"name\":\"Remorques industrielles | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"datePublished\":\"2015-05-06T18:09:50+00:00\",\"dateModified\":\"2020-07-10T00:36:35+00:00\",\"description\":\"Gr\\u00e2ce \\u00e0 un rayon de braquage r\\u00e9duit et \\u00e0 une capacit\\u00e9 de travail imposante, nos remorques industrielles \\u00e0 timon d\\u2019attelage sont puissantes et robustes, tout en \\u00e9tant hautement man\\u0153uvrables.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/fr\/remorques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/fr\/remorques\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/remorques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Remorques industrielles\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remorques industrielles | Motrec","description":"Gr\u00e2ce \u00e0 un rayon de braquage r\u00e9duit et \u00e0 une capacit\u00e9 de travail imposante, nos remorques industrielles \u00e0 timon d\u2019attelage sont puissantes et robustes, tout en \u00e9tant hautement man\u0153uvrables.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Remorques industrielles | Motrec","og_description":"Gr\u00e2ce \u00e0 un rayon de braquage r\u00e9duit et \u00e0 une capacit\u00e9 de travail imposante, nos remorques industrielles \u00e0 timon d\u2019attelage sont puissantes et robustes, tout en \u00e9tant hautement man\u0153uvrables.","og_url":"https:\/\/dev.motrec.com\/fr\/remorques\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_modified_time":"2020-07-10T00:36:35+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/fr\/remorques\/#webpage","url":"https:\/\/dev.motrec.com\/fr\/remorques\/","name":"Remorques industrielles | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"datePublished":"2015-05-06T18:09:50+00:00","dateModified":"2020-07-10T00:36:35+00:00","description":"Gr\u00e2ce \u00e0 un rayon de braquage r\u00e9duit et \u00e0 une capacit\u00e9 de travail imposante, nos remorques industrielles \u00e0 timon d\u2019attelage sont puissantes et robustes, tout en \u00e9tant hautement man\u0153uvrables.","breadcrumb":{"@id":"https:\/\/dev.motrec.com\/fr\/remorques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/fr\/remorques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/fr\/remorques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Remorques industrielles"}]}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages\/11336"}],"collection":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/comments?post=11336"}],"version-history":[{"count":5,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages\/11336\/revisions"}],"predecessor-version":[{"id":15198,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages\/11336\/revisions\/15198"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/media?parent=11336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}