{"id":11114,"date":"2014-12-29T15:09:04","date_gmt":"2014-12-29T15:09:04","guid":{"rendered":"https:\/\/motrec.bravad-dev.com\/vehicules\/series\/ms-series\/"},"modified":"2018-05-24T17:50:23","modified_gmt":"2018-05-24T17:50:23","slug":"serie-ms","status":"publish","type":"page","link":"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/","title":{"rendered":"S\u00e9rie MS"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":10944,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"templates\/vehicles-list.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chariots de magasiniers - S\u00e9rie MS de Motrec | Motrec<\/title>\n<meta name=\"description\" content=\"S\u00e9rie MS de Motrec \u2013 Nos chariots de magasiniers polyvalents peuvent supporter de lourdes charges avec une maniabilit\u00e9 surprenante.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chariots de magasiniers - S\u00e9rie MS de Motrec | Motrec\" \/>\n<meta property=\"og:description\" content=\"S\u00e9rie MS de Motrec \u2013 Nos chariots de magasiniers polyvalents peuvent supporter de lourdes charges avec une maniabilit\u00e9 surprenante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-24T17:50:23+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/\",\"name\":\"Chariots de magasiniers - S\\u00e9rie MS de Motrec | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"datePublished\":\"2014-12-29T15:09:04+00:00\",\"dateModified\":\"2018-05-24T17:50:23+00:00\",\"description\":\"S\\u00e9rie MS de Motrec \\u2013 Nos chariots de magasiniers polyvalents peuvent supporter de lourdes charges avec une maniabilit\\u00e9 surprenante.\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\\u00e9hicules\",\"item\":\"https:\/\/dev.motrec.com\/fr\/vehicules\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Series\",\"item\":\"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"S\\u00e9rie MS\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chariots de magasiniers - S\u00e9rie MS de Motrec | Motrec","description":"S\u00e9rie MS de Motrec \u2013 Nos chariots de magasiniers polyvalents peuvent supporter de lourdes charges avec une maniabilit\u00e9 surprenante.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Chariots de magasiniers - S\u00e9rie MS de Motrec | Motrec","og_description":"S\u00e9rie MS de Motrec \u2013 Nos chariots de magasiniers polyvalents peuvent supporter de lourdes charges avec une maniabilit\u00e9 surprenante.","og_url":"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_modified_time":"2018-05-24T17:50:23+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/#webpage","url":"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/","name":"Chariots de magasiniers - S\u00e9rie MS de Motrec | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"datePublished":"2014-12-29T15:09:04+00:00","dateModified":"2018-05-24T17:50:23+00:00","description":"S\u00e9rie MS de Motrec \u2013 Nos chariots de magasiniers polyvalents peuvent supporter de lourdes charges avec une maniabilit\u00e9 surprenante.","breadcrumb":{"@id":"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/serie-ms\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/fr\/"},{"@type":"ListItem","position":2,"name":"V\u00e9hicules","item":"https:\/\/dev.motrec.com\/fr\/vehicules\/"},{"@type":"ListItem","position":3,"name":"Series","item":"https:\/\/dev.motrec.com\/fr\/vehicules\/series\/"},{"@type":"ListItem","position":4,"name":"S\u00e9rie MS"}]}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages\/11114"}],"collection":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/comments?post=11114"}],"version-history":[{"count":1,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages\/11114\/revisions"}],"predecessor-version":[{"id":11161,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages\/11114\/revisions\/11161"}],"up":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/pages\/10944"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/fr\/wp-json\/wp\/v2\/media?parent=11114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}