{"id":15696,"date":"2019-06-17T17:07:22","date_gmt":"2019-06-17T17:07:22","guid":{"rendered":"https:\/\/www.motrec.com\/?p=15696\/"},"modified":"2019-06-17T17:08:29","modified_gmt":"2019-06-17T17:08:29","slug":"discurso-expo-dex","status":"publish","type":"post","link":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/","title":{"rendered":"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\u00e1 el discurso de apertura del coloquio Expo DEX"},"content":{"rendered":"<p>Blair McIntosh cuenta con una gran experiencia en cuanto al desarrollo de empresas. Desde su llegada con Motrec en 2011, ha llegado a ser una de las empresas m\u00e1s reconocidas en la industria de veh\u00edculos el\u00e9ctricos comerciales e industriales.<\/p>\n<p>Su trayectoria profesional como empresario apasionado e innovador no se ha limitado por lo cual. Su pericia pasa por el desarrollo de empresas, la venta y el m\u00e1rketing, la negociaci\u00f3n, el servicio a la clientela y la planificaci\u00f3n estrat\u00e9gica. Apoya orgullosamente al talento de la nueva generaci\u00f3n de empresarios que favorecen cambios positivos en el mundo por sus proyectos innovadores.<\/p>\n<p>Por la combinaci\u00f3n de todos esos elementos, consideramos que es un conferencista ideal para el pr\u00f3ximo evento <em>Design Engineering Expo<\/em> (DEX Expo) que tomar\u00e1 lugar este 19 de junio 2019 en Sherbrooke.<\/p>\n<ul>\n<li>La industria de fabricaci\u00f3n en Canad\u00e1: la experiencia de Motrec<\/li>\n<li>La diferenciaci\u00f3n: la clave para ser competitivo en el mercado americano<\/li>\n<li>Favorecer la industria 4.0 para mejorar la productividad<\/li>\n<li>Adoptar una estrategia para mejorar constantemente y tener una visi\u00f3n de producci\u00f3n eficiente<\/li>\n<li>Mantenerse \u00e1gil a pesar del crecimiento acelerado<\/li>\n<li>Porqu\u00e9 la innovaci\u00f3n es m\u00e1s importe de lo que se puede creer<\/li>\n<li>Como reclutar empleados competentes y crear un ambiente favorable a largo plazo<\/li>\n<li>Los puntos positivos y los puntos negativos inesperados de una nueva construcci\u00f3n de f\u00e1brica de \u00faltima tecnolog\u00eda<\/li>\n<\/ul>\n<blockquote class=\"\"><p>\u201cEn Motrec, creamos y fabricamos veh\u00edculos industriales el\u00e9ctricos para favorecer el transporte horizontal de mercanc\u00eda y pasajeros. Es nuestro principal objetivo apoyado por nuestra cultura novadora, el trabajo en equipo, la agilidad y el servicio a la clientela. Es lo que nos permite entregar de manera constante los veh\u00edculos conforme a las expectativas de nuestros clientes, siendo eficientes y seguros.<\/p>\n<p>Todas las lecciones que aprendimos en el camino hacia el \u00e9xito pueden aplicarse a otras empresas e industrias. En esta presentaci\u00f3n, tengo por objetivo que la gente tenga una mejor percepci\u00f3n de la tecnolog\u00eda y que tambi\u00e9n entiendan como puede estimular el desarrollo.\u201d<\/p>\n<p>&#8211; Blair McIntosh, presidente y director ejecutivo de Motrec<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Ese coloquio regional juntar\u00e1 una multitud de dise\u00f1adores e ingenieros reputados para abordar varios temas sobre las m\u00e1s recientes tecnolog\u00edas novadoras que estimulan el desarrollo empresarial.<\/p>\n","protected":false},"author":2,"featured_media":15680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[36],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\u00e1 el discurso de apertura del coloquio Expo DEX | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\u00e1 el discurso de apertura del coloquio Expo DEX | Motrec\" \/>\n<meta property=\"og:description\" content=\"Ese coloquio regional juntar\u00e1 una multitud de dise\u00f1adores e ingenieros reputados para abordar varios temas sobre las m\u00e1s recientes tecnolog\u00edas novadoras que estimulan el desarrollo empresarial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-17T17:07:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-17T17:08:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/06\/blair-dex.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"motrec\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#primaryimage\",\"inLanguage\":\"es-ES\",\"url\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/06\/blair-dex.jpg\",\"contentUrl\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/06\/blair-dex.jpg\",\"width\":835,\"height\":470},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/\",\"name\":\"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\\u00e1 el discurso de apertura del coloquio Expo DEX | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#primaryimage\"},\"datePublished\":\"2019-06-17T17:07:22+00:00\",\"dateModified\":\"2019-06-17T17:08:29+00:00\",\"author\":{\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\\u00e1 el discurso de apertura del coloquio Expo DEX\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad\",\"name\":\"motrec\",\"url\":\"https:\/\/dev.motrec.com\/es\/author\/motrec\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\u00e1 el discurso de apertura del coloquio Expo DEX | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\u00e1 el discurso de apertura del coloquio Expo DEX | Motrec","og_description":"Ese coloquio regional juntar\u00e1 una multitud de dise\u00f1adores e ingenieros reputados para abordar varios temas sobre las m\u00e1s recientes tecnolog\u00edas novadoras que estimulan el desarrollo empresarial.","og_url":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_published_time":"2019-06-17T17:07:22+00:00","article_modified_time":"2019-06-17T17:08:29+00:00","og_image":[{"width":835,"height":470,"url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/06\/blair-dex.jpg","type":"image\/jpeg"}],"twitter_misc":{"Escrito por":"motrec","Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"ImageObject","@id":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#primaryimage","inLanguage":"es-ES","url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/06\/blair-dex.jpg","contentUrl":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2019\/06\/blair-dex.jpg","width":835,"height":470},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#webpage","url":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/","name":"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\u00e1 el discurso de apertura del coloquio Expo DEX | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#primaryimage"},"datePublished":"2019-06-17T17:07:22+00:00","dateModified":"2019-06-17T17:08:29+00:00","author":{"@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad"},"breadcrumb":{"@id":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/es\/discurso-expo-dex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/es\/"},{"@type":"ListItem","position":2,"name":"El presidente y director ejecutivo de Motrec, Blair McIntosh, efectuar\u00e1 el discurso de apertura del coloquio Expo DEX"}]},{"@type":"Person","@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/8b32065a76794c29b1113115e5df64ad","name":"motrec","url":"https:\/\/dev.motrec.com\/es\/author\/motrec\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/15696"}],"collection":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/comments?post=15696"}],"version-history":[{"count":2,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/15696\/revisions"}],"predecessor-version":[{"id":15698,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/15696\/revisions\/15698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media\/15680"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media?parent=15696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/categories?post=15696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/tags?post=15696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}