{"id":14789,"date":"2018-12-03T15:38:50","date_gmt":"2018-12-03T15:38:50","guid":{"rendered":"https:\/\/www.motrec.com\/?p=14789\/"},"modified":"2018-12-03T15:38:50","modified_gmt":"2018-12-03T15:38:50","slug":"nuevo-sitio-web-espanol","status":"publish","type":"post","link":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/","title":{"rendered":"Bienvenidos al nuevo sitio web Motrec en espa\u00f1ol"},"content":{"rendered":"<p>Motrec se siente orgulloso de proveer <a href=\"https:\/\/www.motrec.com\/es\/vehiculos\/\">veh\u00edculos el\u00e9ctricos industriales<\/a> a clientes en todo el mundo, quienes buscan herramientas resistentes con las que pueden hacer su trabajo de forma segura y confiable. Para Motrec, Am\u00e9rica Latina es un mercado que crece con rapidez, en especial M\u00e9xico, donde servimos a varios clientes de la industria automotriz, tales como Chrysler, Volkswagen, Mazda, General Motors y Ford.<\/p>\n<blockquote><p>\u201cLa cultura latinoamericana comparte un gran n\u00famero de maravillosas similitudes con la cultura francocanadiense. Todos en Motrec estamos realmente agradecidos por la confianza que las empresas hispanohablantes han depositado en nuestros veh\u00edculos y en nuestra organizaci\u00f3n. Simplificar sus interacciones con Motrec refleja el valor que le damos a esta relaci\u00f3n.\u201d<\/p>\n<p>&#8211; Robin Charest, EMBA, Director de Ventas y Desarrollo de Negocios en Canad\u00e1<\/p><\/blockquote>\n<p>Para satisfacer las necesidades de nuestros usuarios finales y distribuidores autorizados de habla hispana, hemos creado la <a href=\"https:\/\/www.motrec.com\/es\/\">versi\u00f3n en espa\u00f1ol de nuestro sitio web<\/a> y de documentos relacionados, tales como el folleto corporativo y las fichas t\u00e9cnicas de los veh\u00edculos. Tambi\u00e9n contamos con personal hispanohablante capacitado, que puede responder a cualquier pregunta tanto de clientes como de distribuidores, y que adem\u00e1s puede ofrecer informaci\u00f3n sobre nuestras opciones para personalizar su veh\u00edculo Motrec.<\/p>\n<blockquote><p>\u201cComo l\u00edder global de veh\u00edculos el\u00e9ctricos industriales, Motrec est\u00e1 abierto al mundo y trabajamos duro para facilitar el d\u00eda a d\u00eda de nuestros clientes, sin importar donde est\u00e9n. Era una decisi\u00f3n obvia adaptar nuestra oferta para satisfacer las necesidades de distribuidores y usuarios finales en Am\u00e9rica Latina y Espa\u00f1a.\u201d<\/p>\n<p>&#8211; Blair McIntosh, Presidente<\/p><\/blockquote>\n<p><strong>Motrec se enorgullece de servir a clientes y distribuidores en los siguientes pa\u00edses hispanohablantes:<\/strong><\/p>\n<ul>\n<li>M\u00e9xico<\/li>\n<li>Espa\u00f1a<\/li>\n<li>Argentina<\/li>\n<li>Per\u00fa<\/li>\n<li>Venezuela<\/li>\n<li>Chile<\/li>\n<li>Guatemala<\/li>\n<li>Honduras<\/li>\n<li>Nicaragua<\/li>\n<li>Panam\u00e1<\/li>\n<li>Uruguay<\/li>\n<li>El Salvador<\/li>\n<li>Ecuador<\/li>\n<li>Costa Rica<\/li>\n<li>Rep\u00fablica Dominicana<\/li>\n<li>Cuba<\/li>\n<li>Colombia<\/li>\n<\/ul>\n<p>Motrec se ha convertido en un experto global en transporte horizontal, gracias a su firme enfoque en la construcci\u00f3n de los m\u00e1s robustos tractores de arrastre, veh\u00edculos de carga y stock chasers el\u00e9ctricos del mundo, durante m\u00e1s de 30 a\u00f1os.<\/p>\n<p>\u00bfDesea m\u00e1s informaci\u00f3n? <a href=\"https:\/\/www.motrec.com\/es\/concesionarios\/encontrar-un-concesionario\/\">Encuentre un distribuidor Motrec cerca a usted<\/a> o <a href=\"https:\/\/www.motrec.com\/es\/contacto\/\">cont\u00e1ctenos <\/a>para conocer m\u00e1s sobre nuestro contenido en espa\u00f1ol.<\/p>\n<p><a class=\"btn btn_orange1 btn_orange1_b\" href=\"https:\/\/www.motrec.com\/es\/\"><strong>Visite el sitio web en espa\u00f1ol<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Motrec se siente orgulloso de proveer veh\u00edculos el\u00e9ctricos industriales a clientes en todo el mundo, quienes buscan herramientas resistentes con las que pueden hacer su trabajo de forma segura y confiable. Para Motrec, Am\u00e9rica Latina es un mercado que crece con rapidez, en especial M\u00e9xico, donde servimos a varios clientes de la industria automotriz, tales [&hellip;]<\/p>\n","protected":false},"author":100,"featured_media":14904,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[31],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bienvenidos al nuevo sitio web Motrec en espa\u00f1ol | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bienvenidos al nuevo sitio web Motrec en espa\u00f1ol | Motrec\" \/>\n<meta property=\"og:description\" content=\"Motrec se siente orgulloso de proveer veh\u00edculos el\u00e9ctricos industriales a clientes en todo el mundo, quienes buscan herramientas resistentes con las que pueden hacer su trabajo de forma segura y confiable. Para Motrec, Am\u00e9rica Latina es un mercado que crece con rapidez, en especial M\u00e9xico, donde servimos a varios clientes de la industria automotriz, tales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-03T15:38:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/11\/BlogPost-Header-ESP-V2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime Champagne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#primaryimage\",\"inLanguage\":\"es-ES\",\"url\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/11\/BlogPost-Header-ESP-V2.jpg\",\"contentUrl\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/11\/BlogPost-Header-ESP-V2.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/\",\"name\":\"Bienvenidos al nuevo sitio web Motrec en espa\\u00f1ol | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#primaryimage\"},\"datePublished\":\"2018-12-03T15:38:50+00:00\",\"dateModified\":\"2018-12-03T15:38:50+00:00\",\"author\":{\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bienvenidos al nuevo sitio web Motrec en espa\\u00f1ol\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d\",\"name\":\"Maxime Champagne\",\"url\":\"https:\/\/dev.motrec.com\/es\/author\/maxime\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bienvenidos al nuevo sitio web Motrec en espa\u00f1ol | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Bienvenidos al nuevo sitio web Motrec en espa\u00f1ol | Motrec","og_description":"Motrec se siente orgulloso de proveer veh\u00edculos el\u00e9ctricos industriales a clientes en todo el mundo, quienes buscan herramientas resistentes con las que pueden hacer su trabajo de forma segura y confiable. Para Motrec, Am\u00e9rica Latina es un mercado que crece con rapidez, en especial M\u00e9xico, donde servimos a varios clientes de la industria automotriz, tales [&hellip;]","og_url":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_published_time":"2018-12-03T15:38:50+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/11\/BlogPost-Header-ESP-V2.jpg","type":"image\/jpeg"}],"twitter_misc":{"Escrito por":"Maxime Champagne","Tiempo de lectura":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"ImageObject","@id":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#primaryimage","inLanguage":"es-ES","url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/11\/BlogPost-Header-ESP-V2.jpg","contentUrl":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/11\/BlogPost-Header-ESP-V2.jpg","width":1200,"height":675},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#webpage","url":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/","name":"Bienvenidos al nuevo sitio web Motrec en espa\u00f1ol | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#primaryimage"},"datePublished":"2018-12-03T15:38:50+00:00","dateModified":"2018-12-03T15:38:50+00:00","author":{"@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d"},"breadcrumb":{"@id":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/es\/nuevo-sitio-web-espanol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/es\/"},{"@type":"ListItem","position":2,"name":"Bienvenidos al nuevo sitio web Motrec en espa\u00f1ol"}]},{"@type":"Person","@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d","name":"Maxime Champagne","url":"https:\/\/dev.motrec.com\/es\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/14789"}],"collection":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/comments?post=14789"}],"version-history":[{"count":2,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/14789\/revisions"}],"predecessor-version":[{"id":14791,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/14789\/revisions\/14791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media\/14904"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media?parent=14789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/categories?post=14789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/tags?post=14789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}