{"id":14334,"date":"2018-05-12T17:34:51","date_gmt":"2018-05-12T17:34:51","guid":{"rendered":"https:\/\/www.motrec.com\/hamilton-caster-partnership-trailers\/"},"modified":"2018-11-12T17:08:57","modified_gmt":"2018-11-12T17:08:57","slug":"hamilton-caster-partnership-trailers","status":"publish","type":"post","link":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/","title":{"rendered":"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec"},"content":{"rendered":"<p>Un veh\u00edculo industrial Motrec es de por si un elemento de fuerza; junto con un remolque de calidad Hamilton Caster, es imparable.<\/p>\n<p>Esta nueva colaboraci\u00f3n permite tanto a Motrec como a Hamilton Caster satisfacer las necesidades de sus clientes a un nivel totalmente nuevo. Es una ventaja global, que complementa la oferta de Motrec y que permite a Hamilton Caster tener una relaci\u00f3n privilegiada con un fabricante OEM de veh\u00edculos industriales el\u00e9ctricos. Los distribuidores y clientes son quienes sacar\u00e1n mayor provecho con esta uni\u00f3n, y se beneficiar\u00e1n de una soluci\u00f3n integral, con productos adicionales proporcionados a trav\u00e9s de un punto \u00fanico de contacto.<\/p>\n<p>Motrec y Hamilton Caster son una combinaci\u00f3n perfecta, una asociaci\u00f3n pensada en detalle por ambas partes. En operaci\u00f3n desde 1907, Hamilton Caster es una compa\u00f1\u00eda acreditada con vasta experiencia y conocimientos, comprometida con la confianza, la seguridad y de valores arraigados, tal como Motrec.<\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-13199\" src=\"https:\/\/www.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2.jpg\" alt=\"\" width=\"1200\" height=\"400\" srcset=\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2.jpg 1200w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-300x100.jpg 300w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-768x256.jpg 768w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-1024x341.jpg 1024w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-671x224.jpg 671w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-600x200.jpg 600w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-320x107.jpg 320w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-218x73.jpg 218w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-121x40.jpg 121w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-83x28.jpg 83w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-1040x347.jpg 1040w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-960x320.jpg 960w, https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-HamiltonTrailers-Banner-2-820x273.jpg 820w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p>Esta nueva colaboraci\u00f3n significar\u00e1 la adici\u00f3n de cinco nuevos remolques dise\u00f1ados y fabricados por Hamilton Caster para Motrec International. Esta estrategia de marca compartida se a\u00f1adir\u00e1 a la oferta actual de remolques Motrec.<\/p>\n<blockquote><p>\u201cMe emociona mucho pensar en la alianza entre Motrec y Hamilton Caster. Decimos que nuestros remolques son los m\u00e1s fuertes del planeta, y nos hemos aliado con un socio fabricante de veh\u00edculos industriales el\u00e9ctricos que piensa como nosotros. Los clientes encontrar\u00e1n una soluci\u00f3n resistente y sin preocupaciones para el manejo integral de materiales, en un solo lugar\u201d.<\/p>\n<p><strong>\u2013 Steve Lippert, Vice-presidente ejecutivo, Hamilton Caster<\/strong><\/p><\/blockquote>\n<p>Esta nueva y amplia gama de remolques, junto con la m\u00e1s grande l\u00ednea de veh\u00edculos industriales el\u00e9ctricos, har\u00e1n de Motrec el m\u00e1s completo y especializado fabricante de equipos originales (OEM) en la industria de manejo horizontal de materiales.<\/p>\n<blockquote><p>&#8220;Estamos convencidos de que Hamilton Caster es el socio ideal. Su capacidad para fabricar productos resistentes y a la medida est\u00e1 directamente relacionada con nuestros valores y compromiso. Los remolques ser\u00e1n un gran complemento a nuestra oferta, y enviar\u00e1n un mensaje claro a la industria: ahora, Motrec International es el lugar integral para la adquisici\u00f3n de tractores de arrastre, veh\u00edculos de transporte de personal y carga, stockchasers, y ahora, remolques.<\/p>\n<p>\u2013 Robin Charest, Director de Ventas y Desarrollo de Negocios de Motrec International.<\/p><\/blockquote>\n<p>Los equipos de Hamilton Caster y Motrec est\u00e1n muy emocionados con esta nueva alianza y con el sinf\u00edn de oportunidades para todos los colaboradores. Ambos conf\u00edan en que los clientes se beneficiar\u00e1n enormemente de esta mejorada oferta.<\/p>\n<p>&nbsp;<\/p>\n<h4>Sobre Hamilton Caster<\/h4>\n<p>Hamilton Caster es un fabricante l\u00edder de ruedas pivotantes, ruedas, plataformas rodantes y remolques. Fundada en 1907, Hamilton Caster es due\u00f1a de una reconocida reputaci\u00f3n dada la calidad de sus productos, su excelente servicio y sus equipos dise\u00f1ados a la medida.<\/p>\n<h4>Sobre Motrec International<\/h4>\n<p>Motrec International Inc. es un reconocido fabricante de veh\u00edculos industriales el\u00e9ctricos. Con sede en Sherbrooke (Quebec, Canad\u00e1), Motrec se especializa en veh\u00edculos de vanguardia elaborados para satisfacer las necesidades de los principales actores de la industria. Con un nombre que se asocia a durabilidad, resistencia y confianza, Motrec es l\u00edder, tanto en la industria de manejo de material y equipo, como en la industria de transporte de pasajeros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para Motrec, el a\u00f1o 2018 se perfila como un punto crucial. Adem\u00e1s de nuestra nueva planta, esta nueva alianza con Hamilton Caster, fabricantes reconocidos de ruedas pivotantes, ruedas, carros y remolques, abre un sinn\u00famero de posibilidades a nuevos productos y m\u00e1s opciones para todos los implicados.<\/p>\n","protected":false},"author":100,"featured_media":13174,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[26],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec | Motrec\" \/>\n<meta property=\"og:description\" content=\"Para Motrec, el a\u00f1o 2018 se perfila como un punto crucial. Adem\u00e1s de nuestra nueva planta, esta nueva alianza con Hamilton Caster, fabricantes reconocidos de ruedas pivotantes, ruedas, carros y remolques, abre un sinn\u00famero de posibilidades a nuevos productos y m\u00e1s opciones para todos los implicados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-12T17:34:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-12T17:08:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-Header-HamiltonTrailers-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maxime Champagne\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#primaryimage\",\"inLanguage\":\"es-ES\",\"url\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-Header-HamiltonTrailers-1.jpg\",\"contentUrl\":\"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-Header-HamiltonTrailers-1.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/\",\"name\":\"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#primaryimage\"},\"datePublished\":\"2018-05-12T17:34:51+00:00\",\"dateModified\":\"2018-11-12T17:08:57+00:00\",\"author\":{\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d\"},\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d\",\"name\":\"Maxime Champagne\",\"url\":\"https:\/\/dev.motrec.com\/es\/author\/maxime\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec | Motrec","og_description":"Para Motrec, el a\u00f1o 2018 se perfila como un punto crucial. Adem\u00e1s de nuestra nueva planta, esta nueva alianza con Hamilton Caster, fabricantes reconocidos de ruedas pivotantes, ruedas, carros y remolques, abre un sinn\u00famero de posibilidades a nuevos productos y m\u00e1s opciones para todos los implicados.","og_url":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_published_time":"2018-05-12T17:34:51+00:00","article_modified_time":"2018-11-12T17:08:57+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-Header-HamiltonTrailers-1.jpg","type":"image\/jpeg"}],"twitter_misc":{"Escrito por":"Maxime Champagne","Tiempo de lectura":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"ImageObject","@id":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#primaryimage","inLanguage":"es-ES","url":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-Header-HamiltonTrailers-1.jpg","contentUrl":"https:\/\/dev.motrec.com\/wp-content\/uploads\/2018\/02\/BlogPost-Header-HamiltonTrailers-1.jpg","width":1200,"height":675},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#webpage","url":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/","name":"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#primaryimage"},"datePublished":"2018-05-12T17:34:51+00:00","dateModified":"2018-11-12T17:08:57+00:00","author":{"@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d"},"breadcrumb":{"@id":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/es\/hamilton-caster-partnership-trailers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/es\/"},{"@type":"ListItem","position":2,"name":"Remolques resistentes, seguros y a la medida, fabricados exclusivamente por Hamilton Caster para Motrec"}]},{"@type":"Person","@id":"https:\/\/dev.motrec.com\/#\/schema\/person\/24e65628d880248cf6749344f975051d","name":"Maxime Champagne","url":"https:\/\/dev.motrec.com\/es\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/14334"}],"collection":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/comments?post=14334"}],"version-history":[{"count":2,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/14334\/revisions"}],"predecessor-version":[{"id":14337,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/posts\/14334\/revisions\/14337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media\/13174"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media?parent=14334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/categories?post=14334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/tags?post=14334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}