{"id":15605,"date":"2019-04-24T16:13:20","date_gmt":"2019-04-24T16:13:20","guid":{"rendered":"https:\/\/www.motrec.com\/?page_id=15605\/"},"modified":"2019-04-24T16:13:20","modified_gmt":"2019-04-24T16:13:20","slug":"mt-310","status":"publish","type":"page","link":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/","title":{"rendered":"MT-310"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":100,"featured_media":0,"parent":13986,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/vehicle-full-view.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MT-310 | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MT-310 | Motrec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/\",\"name\":\"MT-310 | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"datePublished\":\"2019-04-24T16:13:20+00:00\",\"dateModified\":\"2019-04-24T16:13:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veh\\u00edculos\",\"item\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Series\",\"item\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"MT Series\",\"item\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"MT-310\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MT-310 | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"MT-310 | Motrec","og_url":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/#webpage","url":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/","name":"MT-310 | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"datePublished":"2019-04-24T16:13:20+00:00","dateModified":"2019-04-24T16:13:20+00:00","breadcrumb":{"@id":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/mt-310\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/es\/"},{"@type":"ListItem","position":2,"name":"Veh\u00edculos","item":"https:\/\/dev.motrec.com\/es\/vehiculos\/"},{"@type":"ListItem","position":3,"name":"Series","item":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/"},{"@type":"ListItem","position":4,"name":"MT Series","item":"https:\/\/dev.motrec.com\/es\/vehiculos\/series\/mt-series\/"},{"@type":"ListItem","position":5,"name":"MT-310"}]}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/15605"}],"collection":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/users\/100"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/comments?post=15605"}],"version-history":[{"count":1,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/15605\/revisions"}],"predecessor-version":[{"id":15606,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/15605\/revisions\/15606"}],"up":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/13986"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media?parent=15605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}