{"id":14714,"date":"2014-08-12T19:32:45","date_gmt":"2014-08-12T19:32:45","guid":{"rendered":"https:\/\/www.motrec.com\/vehiculos\/types\/"},"modified":"2021-06-08T14:12:05","modified_gmt":"2021-06-08T14:12:05","slug":"tipos","status":"publish","type":"page","link":"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/","title":{"rendered":"Tipos de veh\u00edculos"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":13917,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"templates\/vehicles-types.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Veh\u00edculos el\u00e9ctricos industriales: equipos de manipulaci\u00f3n de materiales | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veh\u00edculos el\u00e9ctricos industriales: equipos de manipulaci\u00f3n de materiales | Motrec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-08T14:12:05+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/\",\"name\":\"Veh\\u00edculos el\\u00e9ctricos industriales: equipos de manipulaci\\u00f3n de materiales | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"datePublished\":\"2014-08-12T19:32:45+00:00\",\"dateModified\":\"2021-06-08T14:12:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veh\\u00edculos\",\"item\":\"https:\/\/dev.motrec.com\/es\/vehiculos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tipos de veh\\u00edculos\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veh\u00edculos el\u00e9ctricos industriales: equipos de manipulaci\u00f3n de materiales | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Veh\u00edculos el\u00e9ctricos industriales: equipos de manipulaci\u00f3n de materiales | Motrec","og_url":"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_modified_time":"2021-06-08T14:12:05+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/#webpage","url":"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/","name":"Veh\u00edculos el\u00e9ctricos industriales: equipos de manipulaci\u00f3n de materiales | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"datePublished":"2014-08-12T19:32:45+00:00","dateModified":"2021-06-08T14:12:05+00:00","breadcrumb":{"@id":"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/es\/vehiculos\/tipos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/es\/"},{"@type":"ListItem","position":2,"name":"Veh\u00edculos","item":"https:\/\/dev.motrec.com\/es\/vehiculos\/"},{"@type":"ListItem","position":3,"name":"Tipos de veh\u00edculos"}]}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/14714"}],"collection":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/comments?post=14714"}],"version-history":[{"count":5,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/14714\/revisions"}],"predecessor-version":[{"id":18269,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/14714\/revisions\/18269"}],"up":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/13917"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media?parent=14714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}