{"id":13785,"date":"2014-08-13T15:04:55","date_gmt":"2014-08-13T15:04:55","guid":{"rendered":"https:\/\/www.motrec.com\/innovation\/custom-engineering\/"},"modified":"2021-04-08T18:54:07","modified_gmt":"2021-04-08T18:54:07","slug":"ingenieria-personalizada","status":"publish","type":"page","link":"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/","title":{"rendered":"Ingenier\u00eda personalizada"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":13768,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ingenier\u00eda personalizada | Motrec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ingenier\u00eda personalizada | Motrec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/\" \/>\n<meta property=\"og:site_name\" content=\"Motrec\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MotrecIntl\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-08T18:54:07+00:00\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dev.motrec.com\/#website\",\"url\":\"https:\/\/dev.motrec.com\/\",\"name\":\"Motrec\",\"description\":\"Strong by nature\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dev.motrec.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/#webpage\",\"url\":\"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/\",\"name\":\"Ingenier\\u00eda personalizada | Motrec\",\"isPartOf\":{\"@id\":\"https:\/\/dev.motrec.com\/#website\"},\"datePublished\":\"2014-08-13T15:04:55+00:00\",\"dateModified\":\"2021-04-08T18:54:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dev.motrec.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Innovaci\\u00f3n\",\"item\":\"https:\/\/dev.motrec.com\/es\/innovacion\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ingenier\\u00eda personalizada\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ingenier\u00eda personalizada | Motrec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Ingenier\u00eda personalizada | Motrec","og_url":"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/","og_site_name":"Motrec","article_publisher":"https:\/\/www.facebook.com\/MotrecIntl","article_modified_time":"2021-04-08T18:54:07+00:00","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/dev.motrec.com\/#website","url":"https:\/\/dev.motrec.com\/","name":"Motrec","description":"Strong by nature","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dev.motrec.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/#webpage","url":"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/","name":"Ingenier\u00eda personalizada | Motrec","isPartOf":{"@id":"https:\/\/dev.motrec.com\/#website"},"datePublished":"2014-08-13T15:04:55+00:00","dateModified":"2021-04-08T18:54:07+00:00","breadcrumb":{"@id":"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/dev.motrec.com\/es\/innovacion\/ingenieria-personalizada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dev.motrec.com\/es\/"},{"@type":"ListItem","position":2,"name":"Innovaci\u00f3n","item":"https:\/\/dev.motrec.com\/es\/innovacion\/"},{"@type":"ListItem","position":3,"name":"Ingenier\u00eda personalizada"}]}]}},"_links":{"self":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/13785"}],"collection":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/comments?post=13785"}],"version-history":[{"count":6,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/13785\/revisions"}],"predecessor-version":[{"id":18008,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/13785\/revisions\/18008"}],"up":[{"embeddable":true,"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/pages\/13768"}],"wp:attachment":[{"href":"https:\/\/dev.motrec.com\/es\/wp-json\/wp\/v2\/media?parent=13785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}